{"id":14683,"date":"2020-02-21T08:10:31","date_gmt":"2020-02-21T07:10:31","guid":{"rendered":"https:\/\/www.my-netti.com\/spare-part\/head-support-b\/"},"modified":"2026-05-07T11:42:48","modified_gmt":"2026-05-07T09:42:48","slug":"kopfstuetze-b","status":"publish","type":"spare-part","link":"https:\/\/www.my-netti.com\/de\/spare-part\/kopfstuetze-b\/","title":{"rendered":"Kopfst\u00fctze B"},"parent":0,"template":"","certification":[],"spare-part-category":[266],"wheelchair-category":[1211,1217],"class_list":["post-14683","spare-part","type-spare-part","status-publish","hentry","spare-part-category-kopfstuetzen_de","wheelchair-category-comfort-2","wheelchair-category-power-2"],"primary_categories":[],"app_templates_compare_top_banner_title":"","app_templates_compare_top_banner_body":"","app_templates_compare_top_banner_image":"","app_templates_compare_top_banner_color":"white","app_templates_compare_top_banner_overlay":true,"app_templates_compare_top_banner_hide":false,"app_templates_cookie_policy_top_banner_title":"","app_templates_cookie_policy_top_banner_body":"","app_templates_cookie_policy_top_banner_image":"","app_templates_cookie_policy_top_banner_color":"white","app_templates_cookie_policy_top_banner_overlay":true,"app_templates_cookie_policy_top_banner_hide":false,"app_templates_home_page_home_banner_slides":[],"app_templates_home_page_home_banner_html":"","app_templates_home_page_link_boxes_boxes":[],"app_templates_home_page_link_boxes_cta_box_show_cta":true,"app_templates_home_page_link_boxes_cta_box_title":"","app_templates_home_page_link_boxes_cta_box_body":"","app_templates_home_page_link_boxes_cta_box_icon":"","app_templates_home_page_link_boxes_cta_box_link":{"value":"","url":"","anchor":"","blank":0},"app_templates_home_page_link_boxes_cta_box_html":"","app_templates_home_page_media_text_box_image":"","app_templates_home_page_media_text_box_full_width":false,"app_templates_home_page_media_text_box_pretitle":"","app_templates_home_page_media_text_box_title":"","app_templates_home_page_media_text_box_body":"","app_templates_home_page_media_text_box_link":{"value":"","url":"","anchor":"","blank":0},"app_templates_home_page_media_text_box_hide":false,"app_templates_home_page_article_slider_title":"\u00c4hnliche Artikel","app_templates_home_page_article_slider_show_latest":false,"app_templates_home_page_article_slider_articles":[],"app_templates_home_page_product_slider_title":"\u00c4hnliche Produkte","app_templates_home_page_product_slider_product_kind":"wheelchairs","app_templates_home_page_product_slider_wheelchairs":[],"app_templates_home_page_product_slider_spare_parts":[],"app_templates_home_page_product_slider_all":[],"app_templates_home_page_product_slider_hide_info":false,"app_templates_modules_top_banner_title":"","app_templates_modules_top_banner_body":"","app_templates_modules_top_banner_image":"","app_templates_modules_top_banner_color":"white","app_templates_modules_top_banner_overlay":true,"app_templates_modules_top_banner_hide":false,"app_templates_modules_modules_modules":[],"app_templates_modules_product_items_product":[],"app_post_types_spare_part_product_header_title":"Kopfst\u00fctze B","app_post_types_spare_part_product_header_description":"F\u00fcr Nutzer mit Bedarf an Kopfkontrolle in gekantelter Position.\r\n\r\nKopfst\u00fctze Typ B ist etwas kleiner mit einem gepolsterten Kopfkissen und wird oft f\u00fcr Nutzer mit einer guten Kopfstabilit\u00e4t und \u2013kontrolle eingesetzt. Sie wird oft von eher aktiven Nutzern genutzt, wenn z. B. die Sitz-\/R\u00fcckenkantelung des Rollstuhles benutzt wird oder als einfache L\u00f6sung zum Transport des Nutzers im Auto.","app_post_types_spare_part_product_header_rotate_images":[],"app_post_types_spare_part_product_header_activate_rotate":false,"app_post_types_spare_part_product_header_gallery":["118942"],"app_post_types_spare_part_product_items_html":"","app_post_types_spare_part_product_items_product_tabs":[{"_type":"_","title":"Komplette Kopfst\u00fctze B","tab_key":"tab_5e9969f406769","product_skus":"40881,28383,96601,96586","image":"","products":[]},{"_type":"_","title":"Kopfst\u00fctze mit Horizontalstange","tab_key":"tab_5e9969f40676b","product_skus":"42361,42360,42364,42363,42367,42366","image":"","products":[]},{"_type":"_","title":"Vertikalstange","tab_key":"tab_5e9969f40676c","product_skus":"41401,41402,41403,20509,20282","image":"","products":[]},{"_type":"_","title":"Vertikalstange f\u00fcr Netti AdaptPro Family ","tab_key":"tab_639052b420415","product_skus":"92901","image":"","products":[]},{"_type":"_","title":"Bezug ","tab_key":"tab_5e9969f40676d","product_skus":"40884,27555","image":"","products":[]},{"_type":"_","title":"Zubeh\u00f6r \/ Sonstiges","tab_key":"tab_5e9969f40676e","product_skus":"20282,20063,91056,29305,20852,20097","image":"","products":[]},{"_type":"_","title":"Horizontale Stange f\u00fcr Kopfst\u00fctze B (nur bei Produktion nach 07\/2019)","tab_key":"tab_635910838c420","product_skus":"20318,95740,20372,95741","image":"","products":[]}],"app_post_types_spare_part_info_selling_points_title":"","app_post_types_spare_part_info_selling_points_items":[{"_type":"_","title":"H\u00f6heneinstellung","text":"<img class=\"size-medium wp-image-11122 alignleft\" src=\"\/app\/uploads\/2020\/03\/Head-support-adjustment-600x383.png\" alt=\"\" width=\"300\" height=\"192\" \/>Jede Kopfst\u00fctze kann mit einem Kopfst\u00fctzenadapter an alle erh\u00e4ltlichen Netti Rollst\u00fchle angebracht werden. Um die Kopfst\u00fctze in der H\u00f6he zu verstellen, m\u00fcssen Sie den roten Verriegelungshebel soweit gegen den Uhrzeigersinn \u00f6ffnen, bis Sie\r\ndie Vertikalstange hoch und runter schieben k\u00f6nnen. Bringen Sie die Vertikalstange in die von Ihnen gew\u00fcnschte Position, dann drehen Sie den roten Verriegelungshebel soweit im Uhrzeigersinn bis die Vertikalstange wieder festsitzt. Eine solide Version des Kopfst\u00fctzenadapters aus Aluminium ist verf\u00fcgbar. Mit dieser Ausf\u00fchrung k\u00f6nnen Sie die H\u00f6he mit einer Schraube fixieren, um ungewollte Positionsver\u00e4nderung zu vermeiden."},{"_type":"_","title":"Tiefeneinstellung","text":"<img class=\"size-medium wp-image-11128 alignleft\" src=\"\/app\/uploads\/2020\/03\/Head-support-adjustment2-600x383.png\" alt=\"\" width=\"300\" height=\"192\" \/>Um die Kopfst\u00fctze in der Tiefe einzustellen, \u00f6ffnen Sie den roten Verriegelungshebel der Horizontalstange soweit gegen den Uhrzeigesinn bis sich die Horizontalstange vor und zur\u00fcck schieben l\u00e4sst. Bringen Sie die Horizontalstange in die von Ihnen\u00a0 gew\u00fcnschte Position, dann drehen Sie den roten Verriegelungshebel soweit im Uhrzeigersinn bis die Horizontalstange wieder festsitzt."},{"_type":"_","title":"3D-Einstellung","text":"<img class=\"size-medium wp-image-11134 alignleft\" src=\"\/app\/uploads\/2020\/03\/Head-support-adjustment3-600x383.png\" alt=\"\" width=\"300\" height=\"192\" \/>Als eine weitere Einstellm\u00f6glichkeit k\u00f6nnen Sie die Kopfst\u00fctze in sich frei bewegen. Drehen Sie die rote Sternschraube soweit gegen den Uhrzeigersinn bis sich die\u00a0 Kopfst\u00fctzenpolsterung frei bewegen l\u00e4sst. Bringen Sie die Kopfst\u00fctzenpolsterung in die von Ihnen gew\u00fcnschte Position, dann drehen Sie die rote Sternschraube soweit im Uhrzeigersinn bis die Kopfst\u00fctzenpolsterung wieder festsitzt."},{"_type":"_","title":"Seitenverstellbar","text":"<img class=\"size-medium wp-image-11141 alignleft\" src=\"\/app\/uploads\/2020\/03\/Head-support-adjustment4-600x383.png\" alt=\"\" width=\"300\" height=\"192\" \/>Der Kopfst\u00fctzenadapter kann nach rechts oder links verschoben werden, um die genaue Kopfposition vom Nutzer zu unterst\u00fctzen."},{"_type":"_","title":"Verschiedene Bez\u00fcge","text":"<h5><img class=\"size-medium wp-image-5795 alignleft\" src=\"\/app\/uploads\/2020\/02\/3D-600x600.png\" alt=\"\" width=\"300\" height=\"300\" \/> 3D<\/h5>\r\nAtmungsaktiv, elastisch und verschlei\u00dffest. Die 3D-Gitterstruktur verst\u00e4rkt das Mikroklima, entl\u00fcftet und reduziert den W\u00e4rmestau. Das st\u00e4rkt die Haut und die Widerstandsf\u00e4higkeit des darunter liegenden Gewebes gegen \u00e4u\u00dfere und innere Einwirkungen, wie Druck und Scherkr\u00e4ften. 100 % PES (Polyester).\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n\r\n&nbsp;\r\n<h5><img class=\"size-medium wp-image-5801 alignleft\" src=\"\/app\/uploads\/2020\/02\/Easy-Care-600x600.png\" alt=\"\" width=\"300\" height=\"300\" \/><\/h5>\r\n<h5>EASY CARE<\/h5>\r\nVerschlei\u00dffest, atmungsaktiv, elastisch, einfach zu reinigen und hygienisch. PES (Polyester) + PU."}],"app_post_types_spare_part_info_key_features_features":[],"app_post_types_spare_part_fits_wheelchairs":[],"app_post_types_spare_part_videos_videos":[{"_type":"_","title":"Tiefeneinstellung der Kopfst\u00fctze ","video":"https:\/\/youtu.be\/SaTUuNW04AQ"},{"_type":"_","title":"3D-Verstellung","video":"https:\/\/youtu.be\/tlb2XaFGxis"}],"app_post_types_spare_part_downloads_note":"","app_post_types_spare_part_tab_titles_product_items_tab_title":"","app_post_types_spare_part_tab_titles_product_items_title":"","app_post_types_spare_part_tab_titles_product_items_description":"","app_post_types_spare_part_tab_titles_info_tab_title":"","app_post_types_spare_part_tab_titles_info_title":"","app_post_types_spare_part_tab_titles_info_description":"","app_post_types_spare_part_tab_titles_fits_tab_title":"","app_post_types_spare_part_tab_titles_fits_title":"","app_post_types_spare_part_tab_titles_fits_description":"","app_post_types_spare_part_tab_titles_videos_tab_title":"","app_post_types_spare_part_tab_titles_videos_title":"","app_post_types_spare_part_tab_titles_videos_description":"","app_post_types_spare_part_tab_titles_downloads_tab_title":"","app_post_types_spare_part_tab_titles_downloads_title":"","app_post_types_spare_part_tab_titles_downloads_description":"","app_post_types_spare_part_modules_modules":[{"_type":"image","image":""}],"app_post_types_spare_part_product_slider_title":"Related Products","app_post_types_spare_part_product_slider_product_kind":"wheelchairs","app_post_types_spare_part_product_slider_wheelchairs":[],"app_post_types_spare_part_product_slider_spare_parts":[],"app_post_types_spare_part_product_slider_all":[],"app_post_types_spare_part_product_slider_hide_info":false,"app_post_types_spare_part_archive_info_image":"5665","app_post_types_spare_part_archive_info_excerpt":"Klein","app_post_types_spare_part_archive_info_html":"","app_post_types_spare_part_tags_tags":"","_links":{"self":[{"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/spare-part\/14683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/spare-part"}],"about":[{"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/types\/spare-part"}],"version-history":[{"count":10,"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/spare-part\/14683\/revisions"}],"predecessor-version":[{"id":118949,"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/spare-part\/14683\/revisions\/118949"}],"wp:attachment":[{"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/media?parent=14683"}],"wp:term":[{"taxonomy":"certification","embeddable":true,"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/certification?post=14683"},{"taxonomy":"spare-part-category","embeddable":true,"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/spare-part-category?post=14683"},{"taxonomy":"wheelchair-category","embeddable":true,"href":"https:\/\/www.my-netti.com\/de\/wp-json\/wp\/v2\/wheelchair-category?post=14683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}